{"id":24451,"date":"2026-09-02T10:59:44","date_gmt":"2026-09-02T03:59:44","guid":{"rendered":"https:\/\/www.arts.chula.ac.th\/th\/?p=24451"},"modified":"2026-09-02T11:00:44","modified_gmt":"2026-09-02T04:00:44","slug":"%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%ad%e0%b8%b1%e0%b8%81%e0%b8%a9%e0%b8%a3%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%95-18","status":"publish","type":"post","link":"https:\/\/www.arts.chula.ac.th\/th\/arts-activities\/2026\/09\/02\/24451\/","title":{"rendered":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e41\u0e25\u0e30\u0e25\u0e48\u0e32\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e04\u0e13\u0e30\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35"},"content":{"rendered":"\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 14 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2569 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e27\u0e25\u0e32 9.00 &#8211; 11.00 \u0e19. \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e04\u0e13\u0e30\u0e21\u0e19\u0e38\u0e29\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e19\u0e27\u0e19 72 \u0e04\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e41\u0e25\u0e30\u0e25\u0e48\u0e32\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e04\u0e13\u0e30\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2d\u0e20\u0e34\u0e23\u0e14\u0e35 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e40\u0e2a\u0e19\u0e35\u0e22\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e2f \u0e41\u0e25\u0e30\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e2f \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e30 \u0e23\u0e48\u0e27\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e32\u0e18\u0e34\u0e15\u0e01\u0e32\u0e23\u0e25\u0e48\u0e32\u0e21\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19 \u0e13 \u0e2b\u0e49\u0e2d\u0e07 304 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e08\u0e31\u0e01\u0e23\u0e35\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e18\u0e23<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24453\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4949-1024x684.jpg\" alt=\"\" class=\"wp-image-24453\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4949-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4949-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4949-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4949-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4949-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24454\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4953-1024x684.jpg\" alt=\"\" class=\"wp-image-24454\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4953-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4953-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4953-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4953-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4953-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24458\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4962-1024x684.jpg\" alt=\"\" class=\"wp-image-24458\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4962-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4962-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4962-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4962-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4962-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24455\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4969-1024x684.jpg\" alt=\"\" class=\"wp-image-24455\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4969-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4969-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4969-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4969-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4969-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24457\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4973-1024x684.jpg\" alt=\"\" class=\"wp-image-24457\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4973-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4973-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4973-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4973-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4973-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24456\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4985-1024x684.jpg\" alt=\"\" class=\"wp-image-24456\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4985-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4985-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4985-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4985-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4985-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24459\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4991-1024x684.jpg\" alt=\"\" class=\"wp-image-24459\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4991-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4991-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4991-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4991-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4991-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24460\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4994-1024x684.jpg\" alt=\"\" class=\"wp-image-24460\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4994-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4994-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4994-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4994-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_4994-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24461\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5026-1024x684.jpg\" alt=\"\" class=\"wp-image-24461\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5026-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5026-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5026-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5026-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5026-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24463\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5051-1024x684.jpg\" alt=\"\" class=\"wp-image-24463\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5051-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5051-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5051-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5051-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5051-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24464\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5060-1024x684.jpg\" alt=\"\" class=\"wp-image-24464\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5060-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5060-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5060-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5060-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5060-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24462\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5066-1024x684.jpg\" alt=\"\" class=\"wp-image-24462\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5066-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5066-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5066-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5066-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5066-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"24465\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5072-1024x684.jpg\" alt=\"\" class=\"wp-image-24465\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5072-1024x684.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5072-300x200.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5072-768x513.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5072-1536x1025.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5072-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"698\" data-id=\"24466\" src=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5082-1024x698.jpg\" alt=\"\" class=\"wp-image-24466\" srcset=\"https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5082-1024x698.jpg 1024w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5082-300x205.jpg 300w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5082-768x524.jpg 768w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5082-1536x1047.jpg 1536w, https:\/\/www.arts.chula.ac.th\/th\/wp-content\/uploads\/2026\/09\/DSC_5082-2048x1396.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 14 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2569 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e27\u0e25\u0e32 9.00 &#8211; 11.00 \u0e19. \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e04\u0e13\u0e30\u0e21\u0e19\u0e38\u0e29\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e19\u0e27\u0e19 72 \u0e04\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e41\u0e25\u0e30\u0e25\u0e48\u0e32\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e04\u0e13\u0e30\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2d\u0e20\u0e34\u0e23\u0e14\u0e35 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e40\u0e2a\u0e19\u0e35\u0e22\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e2f \u0e41\u0e25\u0e30\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e2f \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e30 \u0e23\u0e48\u0e27\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e32\u0e18\u0e34\u0e15\u0e01\u0e32\u0e23\u0e25\u0e48\u0e32\u0e21\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19 \u0e13 \u0e2b\u0e49\u0e2d\u0e07 304 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e08\u0e31\u0e01\u0e23\u0e35\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e18\u0e23<\/p>\n","protected":false},"author":123458,"featured_media":24452,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[127],"class_list":["post-24451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arts-activities","tag-127"],"_links":{"self":[{"href":"https:\/\/www.arts.chula.ac.th\/th\/wp-json\/wp\/v2\/posts\/24451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arts.chula.ac.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arts.chula.ac.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arts.chula.ac.th\/th\/wp-json\/wp\/v2\/users\/123458"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arts.chula.ac.th\/th\/wp-json\/wp\/v2\/comments?post=24451"}],"version-history":[{"count":2,"href":"https:\/\/www.arts.chula.ac.th\/th\/wp-json\/wp\/v2\/posts\/24451\/revisions"}],"predecessor-version":[{"id":24469,"href":"https:\/\/www.arts.chula.ac.th\/th\/wp-json\/wp\/v2\/posts\/24451\/revisions\/24469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arts.chula.ac.th\/th\/wp-json\/wp\/v2\/media\/24452"}],"wp:attachment":[{"href":"https:\/\/www.arts.chula.ac.th\/th\/wp-json\/wp\/v2\/media?parent=24451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arts.chula.ac.th\/th\/wp-json\/wp\/v2\/categories?post=24451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arts.chula.ac.th\/th\/wp-json\/wp\/v2\/tags?post=24451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}